{"id":865,"date":"2026-04-23T18:59:22","date_gmt":"2026-04-23T18:59:22","guid":{"rendered":"https:\/\/test.letsmim.com\/?page_id=865"},"modified":"2026-08-08T14:10:10","modified_gmt":"2026-08-08T14:10:10","slug":"profil","status":"publish","type":"page","link":"https:\/\/letsmim.com\/index.php\/profil\/","title":{"rendered":"Profil"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"635\" height=\"750\" src=\"https:\/\/letsmim.com\/wp-content\/uploads\/2026\/04\/cropped-cropped-A.V_flip.jpg\" alt=\"\" class=\"wp-image-134\" srcset=\"https:\/\/letsmim.com\/wp-content\/uploads\/2026\/04\/cropped-cropped-A.V_flip.jpg 635w, https:\/\/letsmim.com\/wp-content\/uploads\/2026\/04\/cropped-cropped-A.V_flip-254x300.jpg 254w\" sizes=\"auto, (max-width: 635px) 100vw, 635px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h1 class=\"wp-block-heading has-black-color has-text-color has-link-color wp-elements-1\">Dr. Angelica V. Marte<\/h1>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Dr. Angelica V. Marte ist Wissenschaftlerin, F\u00fchrungskr\u00e4fteentwicklerin, Executive Coach und Unternehmerin. Seit \u00fcber 25 Jahren arbeitet sie mit internationalen Unternehmen und Universit\u00e4ten zu Leadership, Zusammenarbeit, Diversit\u00e4t und Netzwerken. Sie forschte und publizierte unter anderem an der Universit\u00e4t Witten\/Herdecke, der MIT Sloan School of Management und der Universit\u00e4t Z\u00fcrich<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Heute lehrt und forscht sie an der Zeppelin Universit\u00e4t, der Steinbeis-Hochschule, der FHWien der WKW und der Karlshochschule. Sie begleitet F\u00fchrungskr\u00e4fte und Organisationen in Entwicklungs- und Ver\u00e4nderungsprozessen. Im Zentrum ihrer Arbeit steht die Frage, wie Menschen in einer zunehmend komplexen und von KI gepr\u00e4gten Welt gemeinsam bessere Entscheidungen treffen \u2013 und welche Rolle Urteilskraft, Verantwortung und unterschiedliche Perspektiven in der F\u00fchrung dabei spielen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dr. Angelica V. Marte Dr. Angelica V. Marte ist Wissenschaftlerin, F\u00fchrungskr\u00e4fteentwicklerin, Executive Coach und Unternehmerin. Seit \u00fcber 25 Jahren arbeitet sie mit internationalen Unternehmen und Universit\u00e4ten zu Leadership, Zusammenarbeit, Diversit\u00e4t und Netzwerken. Sie forschte und publizierte unter anderem an der Universit\u00e4t Witten\/Herdecke, der MIT Sloan School of Management und der Universit\u00e4t Z\u00fcrich Heute lehrt und&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/letsmim.com\/index.php\/profil\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-865","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/pages\/865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/comments?post=865"}],"version-history":[{"count":2,"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/pages\/865\/revisions"}],"predecessor-version":[{"id":1024,"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/pages\/865\/revisions\/1024"}],"wp:attachment":[{"href":"https:\/\/letsmim.com\/index.php\/wp-json\/wp\/v2\/media?parent=865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}